{"id":4937,"date":"2024-05-12T20:52:12","date_gmt":"2024-05-12T18:52:12","guid":{"rendered":"http:\/\/media1.marcocueva.com\/Rannebergen-9-1.jpg"},"modified":"2025-03-06T01:13:55","modified_gmt":"2025-03-05T23:13:55","slug":"rannebergen-9-2","status":"inherit","type":"attachment","link":"https:\/\/marcocueva.com\/es\/rannebergen-9-2\/","title":{"rendered":"Pepe"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"categories":[251],"tags":[],"class_list":["post-4937","attachment","type-attachment","status-inherit","hentry","category-new-work"],"jetpack_shortlink":"https:\/\/wp.me\/a63sn4-1hD","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-9-1-scaled.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-9-1-scaled.jpg?fit=720%2C540&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-9-1-scaled.jpg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-9-1-scaled.jpg?resize=720%2C540&amp;ssl=1 720w, https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-9-1-scaled.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-9-1-scaled.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-9-1-scaled.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-9-1-scaled.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-9-1-scaled.jpg?w=2400 2400w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" data-attachment-id=\"4937\" data-permalink=\"https:\/\/marcocueva.com\/es\/rannebergen-9-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-9-1-scaled.jpg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 13 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1695903909&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;5.7&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.0014492753623188&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;,&quot;exposure_bias&quot;:&quot;0\/1&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"Pepe\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;\u00abPepe\u00bb&lt;br \/&gt;\nRannebergen, G\u00f6teborg&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-9-1-scaled.jpg?fit=1024%2C768&amp;ssl=1\" \/><\/a><\/p>\n<div class=\"gallery-frame \">"},"caption":{"rendered":"<p>\u00abPepe\u00bb<br \/>\nRannebergen, G\u00f6teborg<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1920,"file":"Rannebergen-9-1-scaled.jpg","filesize":928622,"sizes":{"medium":{"file":"Rannebergen-9-1-720x540.jpg","width":720,"height":540,"filesize":118913,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-9-1-scaled.jpg?fit=720%2C540&ssl=1"},"large":{"file":"Rannebergen-9-1-1024x768.jpg","width":1024,"height":768,"filesize":199315,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-9-1-scaled.jpg?fit=1024%2C768&ssl=1"},"thumbnail":{"file":"Rannebergen-9-1-150x150.jpg","width":150,"height":150,"filesize":37271,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-9-1-scaled.jpg?resize=150%2C150&ssl=1"},"medium_large":{"file":"Rannebergen-9-1-768x576.jpg","width":768,"height":576,"filesize":129446,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-9-1-scaled.jpg?fit=768%2C576&ssl=1"},"1536x1536":{"file":"Rannebergen-9-1-1536x1152.jpg","width":1536,"height":1152,"filesize":388961,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-9-1-scaled.jpg?fit=1536%2C1152&ssl=1"},"2048x2048":{"file":"Rannebergen-9-1-2048x1536.jpg","width":2048,"height":1536,"filesize":637886,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-9-1-scaled.jpg?fit=2048%2C1536&ssl=1"},"jetpack-portfolio-admin-thumb":{"file":"Rannebergen-9-1-50x50.jpg","width":50,"height":50,"filesize":31619,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-9-1-scaled.jpg?resize=50%2C50&ssl=1"},"full":{"file":"Rannebergen-9-1-scaled.jpg?fit=2560%2C1920&ssl=1","width":2560,"height":1920,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-9-1-scaled.jpg?fit=2560%2C1920&ssl=1"}},"image_meta":{"aperture":"1.5","credit":"","camera":"iPhone 13 Pro Max","caption":"","created_timestamp":"1695903909","copyright":"","focal_length":"5.7","iso":"50","shutter_speed":"0.0014492753623188","title":"","orientation":"0","keywords":[],"exposure_bias":"0\/1","flash":"16"},"original_image":"Rannebergen-9-1.jpg"},"post":null,"source_url":"https:\/\/media1.marcocueva.com\/Rannebergen-9-1-scaled.jpg","_links":{"self":[{"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/media\/4937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/comments?post=4937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/categories?post=4937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/tags?post=4937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}