{"id":103,"date":"2009-12-20T00:48:34","date_gmt":"2009-12-19T22:48:34","guid":{"rendered":"http:\/\/blogg.marcocueva.com\/?p=103"},"modified":"2020-09-22T00:39:15","modified_gmt":"2020-09-21T22:39:15","slug":"quantum-leap-diciembre-2009","status":"publish","type":"post","link":"https:\/\/marcocueva.com\/es\/quantum-leap-diciembre-2009\/","title":{"rendered":"&quot;Quantum Leap?&quot; diciembre 2009"},"content":{"rendered":"<p><a href=\"http:\/\/www.marcocueva.com\/Pages\/ql_200912\/leap.html\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"104\" data-permalink=\"https:\/\/marcocueva.com\/es\/quantum-leap-diciembre-2009\/img_5932\/\" data-orig-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/IMG_5932.jpg?fit=600%2C800&amp;ssl=1\" data-orig-size=\"600,800\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon PowerShot G7&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1259840321&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;7.4&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.1&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_5932\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/IMG_5932.jpg?fit=600%2C800&amp;ssl=1\" class=\"aligncenter size-medium wp-image-104\" title=\"IMG_5932\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/IMG_5932.jpg?resize=225%2C300\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/IMG_5932.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/media1.marcocueva.com\/IMG_5932.jpg?w=600&amp;ssl=1 600w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>Plywood y sobrantes de madera<\/p>\n<div class=\"gallery-frame \">","protected":false},"excerpt":{"rendered":"<p>Plywood y sobrantes de madera<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[13,18],"tags":[127],"class_list":["post-103","post","type-post","status-publish","format-standard","hentry","category-work","category-work-in-progress","tag-nuevos-trabajos"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p63sn4-1F","jetpack-related-posts":[{"id":383,"url":"https:\/\/marcocueva.com\/es\/un-nuevo-comienzo\/","url_meta":{"origin":103,"position":0},"title":"Un Nuevo Comienzo","author":"Marco Cueva","date":"noviembre 22, 2011","format":false,"excerpt":"Ahora que el camello est\u00e1 terminado regreso a mis urnas Despu\u00e9s de m\u00e1s\u00a0 un mes desde mi exposici\u00f3n estoy empezando con nuevos trabajos, mis planes son de producir urnas y ornamentos de jard\u00edn en hierro, estoy haciendo los originales en plywood y luego veremos adonde llegamos.","rel":"","context":"En \u00abTrabajos en Curso\u00bb","block_context":{"text":"Trabajos en Curso","link":"https:\/\/marcocueva.com\/es\/category\/work\/work-in-progress\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3352,"url":"https:\/\/marcocueva.com\/es\/descent\/","url_meta":{"origin":103,"position":1},"title":"Descenso","author":"Marco Cueva","date":"febrero 4, 2016","format":false,"excerpt":"Tarea de invierno, obra en marcha; estoy tratando de terminar este trabajo que ha estado tirado en mi estudio durante los dos \u00faltimos a\u00f1os.","rel":"","context":"En \u00abObra\u00bb","block_context":{"text":"Obra","link":"https:\/\/marcocueva.com\/es\/category\/work\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/media1.marcocueva.com\/nedstigning-1-1.jpg?fit=675%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/media1.marcocueva.com\/nedstigning-1-1.jpg?fit=675%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/media1.marcocueva.com\/nedstigning-1-1.jpg?fit=675%2C1200&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":1467,"url":"https:\/\/marcocueva.com\/es\/behemot-trabajos-de-reconstruccion-de-ultima-hora-2\/","url_meta":{"origin":103,"position":2},"title":"Behemot, trabajos de reconstrucci\u00f3n de\u2026","author":"Marco Cueva","date":"octubre 5, 2013","format":"gallery","excerpt":"Behemot, trabajos de reconstrucci\u00f3n de ultima hora","rel":"","context":"En \u00abObra\u00bb","block_context":{"text":"Obra","link":"https:\/\/marcocueva.com\/es\/category\/work\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_mu7ce3nLGk1sn9hw1o1_r1_1280.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3770,"url":"https:\/\/marcocueva.com\/es\/urnas-actualizacion-del-2016\/","url_meta":{"origin":103,"position":3},"title":"Urnas, Actualizaci\u00f3n del 2016","author":"Marco Cueva","date":"mayo 31, 2016","format":false,"excerpt":"Cuando me queda alg\u00fan tiempo libre: Una vez cada a\u00f1o, por lo menos, actualizo mis esculturas en plywood","rel":"","context":"En \u00abObra\u00bb","block_context":{"text":"Obra","link":"https:\/\/marcocueva.com\/es\/category\/work\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/media1.marcocueva.com\/urn-2016-06-16-01.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/media1.marcocueva.com\/urn-2016-06-16-01.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/media1.marcocueva.com\/urn-2016-06-16-01.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/media1.marcocueva.com\/urn-2016-06-16-01.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/media1.marcocueva.com\/urn-2016-06-16-01.jpg?resize=1050%2C600 3x"},"classes":[]},{"id":143,"url":"https:\/\/marcocueva.com\/es\/nuevos-trabajos\/","url_meta":{"origin":103,"position":4},"title":"Febrero y Marzo","author":"Marco Cueva","date":"marzo 26, 2010","format":false,"excerpt":"Estos\u00a0\u00faltimos\u00a0meses han sido bastante productivos, consegu\u00ed\u00a0terminar\u00a0un par de piezas que hab\u00eda comenzado hace tiempo. Aparte de eso hice dos esculturas m\u00e1s.","rel":"","context":"En \u00abObra\u00bb","block_context":{"text":"Obra","link":"https:\/\/marcocueva.com\/es\/category\/work\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1381,"url":"https:\/\/marcocueva.com\/es\/works-in-progress-february\/","url_meta":{"origin":103,"position":5},"title":"Work in Progress, February","author":"Marco Cueva","date":"febrero 27, 2014","format":"gallery","excerpt":"Obras en curso, febrero","rel":"","context":"En \u00abObra\u00bb","block_context":{"text":"Obra","link":"https:\/\/marcocueva.com\/es\/category\/work\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_n1o37zpnzH1sn9hw1o2_1280.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/posts\/103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/comments?post=103"}],"version-history":[{"count":1,"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/posts\/103\/revisions"}],"predecessor-version":[{"id":2385,"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/posts\/103\/revisions\/2385"}],"wp:attachment":[{"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/media?parent=103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/categories?post=103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/tags?post=103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}