{"id":2595,"date":"2015-05-09T06:46:08","date_gmt":"2015-05-09T06:46:08","guid":{"rendered":"http:\/\/marcocueva.com\/detras-de-los-cerros-oskarslund-karlstad\/"},"modified":"2020-09-22T00:11:52","modified_gmt":"2020-09-21T22:11:52","slug":"detras-de-los-cerros-oskarslund-karlstad","status":"publish","type":"post","link":"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/","title":{"rendered":"\u201cDetr\u00e1s de los Cerros\u201d"},"content":{"rendered":"<p><div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"1200\" data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\\\/\\\/marcocueva.com\\\/es\\\/detras-de-los-cerros-oskarslund-karlstad\\\/&quot;,&quot;likes_blog_id&quot;:89482062}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 1200px; height: 239px;\" data-original-width=\"1200\" data-original-height=\"239\" > <div class=\"gallery-group images-1\" style=\"width: 422px; height: 239px;\" data-original-width=\"422\" data-original-height=\"239\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/attachment\/2596\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"418\"> <meta itemprop=\"height\" content=\"235\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2596\" data-orig-file=\"https:\/\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o2_1280.jpg\" data-orig-size=\"1200,675\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;\\u0090&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1428578515&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.7&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.0003125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o2_1280.jpg?fit=720%2C405&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o2_1280.jpg?fit=1024%2C576&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o2_1280.jpg?w=418&#038;h=235&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o2_1280.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o2_1280.jpg?resize=720%2C405&amp;ssl=1 720w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o2_1280.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o2_1280.jpg?resize=320%2C180&amp;ssl=1 320w\" width=\"418\" height=\"235\" loading=\"lazy\" data-original-width=\"418\" data-original-height=\"235\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"\" style=\"width: 418px; height: 235px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 422px; height: 239px;\" data-original-width=\"422\" data-original-height=\"239\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/attachment\/2597\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"418\"> <meta itemprop=\"height\" content=\"235\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2597\" data-orig-file=\"https:\/\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o6_1280.jpg\" data-orig-size=\"1200,675\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o6_1280.jpg?fit=720%2C405&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o6_1280.jpg?fit=1024%2C576&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o6_1280.jpg?w=418&#038;h=235&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o6_1280.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o6_1280.jpg?resize=720%2C405&amp;ssl=1 720w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o6_1280.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o6_1280.jpg?resize=320%2C180&amp;ssl=1 320w\" width=\"418\" height=\"235\" loading=\"lazy\" data-original-width=\"418\" data-original-height=\"235\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"\" style=\"width: 418px; height: 235px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 356px; height: 239px;\" data-original-width=\"356\" data-original-height=\"239\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/attachment\/2598\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"352\"> <meta itemprop=\"height\" content=\"235\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2598\" data-orig-file=\"https:\/\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o3_1280.jpg\" data-orig-size=\"1200,800\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1430734727&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.9&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o3_1280.jpg?fit=720%2C480&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o3_1280.jpg?fit=1024%2C683&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o3_1280.jpg?w=352&#038;h=235&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o3_1280.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o3_1280.jpg?resize=720%2C480&amp;ssl=1 720w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o3_1280.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o3_1280.jpg?resize=320%2C213&amp;ssl=1 320w\" width=\"352\" height=\"235\" loading=\"lazy\" data-original-width=\"352\" data-original-height=\"235\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"\" style=\"width: 352px; height: 235px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 803px;\" data-original-width=\"1200\" data-original-height=\"803\" > <div class=\"gallery-group images-2\" style=\"width: 710px; height: 803px;\" data-original-width=\"710\" data-original-height=\"803\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/attachment\/2599\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"706\"> <meta itemprop=\"height\" content=\"398\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2599\" data-orig-file=\"https:\/\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o4_1280.jpg\" data-orig-size=\"1200,675\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1430742300&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.9&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.001&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o4_1280.jpg?fit=720%2C405&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o4_1280.jpg?fit=1024%2C576&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o4_1280.jpg?w=706&#038;h=398&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o4_1280.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o4_1280.jpg?resize=720%2C405&amp;ssl=1 720w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o4_1280.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o4_1280.jpg?resize=320%2C180&amp;ssl=1 320w\" width=\"706\" height=\"398\" loading=\"lazy\" data-original-width=\"706\" data-original-height=\"398\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"\" style=\"width: 706px; height: 398px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/attachment\/2600\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"706\"> <meta itemprop=\"height\" content=\"397\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2600\" data-orig-file=\"https:\/\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o5_1280.jpg\" data-orig-size=\"1200,675\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1430743015&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.9&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.0008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o5_1280.jpg?fit=720%2C405&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o5_1280.jpg?fit=1024%2C576&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o5_1280.jpg?w=706&#038;h=397&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o5_1280.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o5_1280.jpg?resize=720%2C405&amp;ssl=1 720w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o5_1280.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o5_1280.jpg?resize=320%2C180&amp;ssl=1 320w\" width=\"706\" height=\"397\" loading=\"lazy\" data-original-width=\"706\" data-original-height=\"397\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"\" style=\"width: 706px; height: 397px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 490px; height: 803px;\" data-original-width=\"490\" data-original-height=\"803\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/attachment\/2601\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"486\"> <meta itemprop=\"height\" content=\"799\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2601\" data-orig-file=\"https:\/\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o7_1280.jpg\" data-orig-size=\"730,1200\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1430843716&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.9&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o7_1280.jpg?fit=438%2C720&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o7_1280.jpg?fit=623%2C1024&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o7_1280.jpg?w=486&#038;h=799&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o7_1280.jpg?w=730&amp;ssl=1 730w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o7_1280.jpg?resize=438%2C720&amp;ssl=1 438w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o7_1280.jpg?resize=623%2C1024&amp;ssl=1 623w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o7_1280.jpg?resize=320%2C526&amp;ssl=1 320w\" width=\"486\" height=\"799\" loading=\"lazy\" data-original-width=\"486\" data-original-height=\"799\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"\" style=\"width: 486px; height: 799px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 597px;\" data-original-width=\"1200\" data-original-height=\"597\" > <div class=\"gallery-group images-1\" style=\"width: 365px; height: 597px;\" data-original-width=\"365\" data-original-height=\"597\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/attachment\/2602\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"361\"> <meta itemprop=\"height\" content=\"593\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2602\" data-orig-file=\"https:\/\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o8_1280.jpg\" data-orig-size=\"730,1200\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1430938539&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.9&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o8_1280.jpg?fit=438%2C720&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o8_1280.jpg?fit=623%2C1024&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o8_1280.jpg?w=361&#038;h=593&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o8_1280.jpg?w=730&amp;ssl=1 730w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o8_1280.jpg?resize=438%2C720&amp;ssl=1 438w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o8_1280.jpg?resize=623%2C1024&amp;ssl=1 623w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o8_1280.jpg?resize=320%2C526&amp;ssl=1 320w\" width=\"361\" height=\"593\" loading=\"lazy\" data-original-width=\"361\" data-original-height=\"593\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"\" style=\"width: 361px; height: 593px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 835px; height: 597px;\" data-original-width=\"835\" data-original-height=\"597\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/attachment\/2603\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"831\"> <meta itemprop=\"height\" content=\"593\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2603\" data-orig-file=\"https:\/\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o10_1280.jpg\" data-orig-size=\"1200,857\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1431088600&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.9&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.0004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o10_1280.jpg?fit=720%2C514&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o10_1280.jpg?fit=1024%2C731&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o10_1280.jpg?w=831&#038;h=593&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o10_1280.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o10_1280.jpg?resize=720%2C514&amp;ssl=1 720w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o10_1280.jpg?resize=1024%2C731&amp;ssl=1 1024w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o10_1280.jpg?resize=320%2C229&amp;ssl=1 320w\" width=\"831\" height=\"593\" loading=\"lazy\" data-original-width=\"831\" data-original-height=\"593\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"\" style=\"width: 831px; height: 593px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 1135px;\" data-original-width=\"1200\" data-original-height=\"1135\" > <div class=\"gallery-group images-1\" style=\"width: 758px; height: 1135px;\" data-original-width=\"758\" data-original-height=\"1135\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/attachment\/2604\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"754\"> <meta itemprop=\"height\" content=\"1131\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2604\" data-orig-file=\"https:\/\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o9_1280.jpg\" data-orig-size=\"800,1200\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1430989745&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.9&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.0008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o9_1280.jpg?fit=480%2C720&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o9_1280.jpg?fit=683%2C1024&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o9_1280.jpg?w=754&#038;h=1131&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o9_1280.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o9_1280.jpg?resize=480%2C720&amp;ssl=1 480w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o9_1280.jpg?resize=683%2C1024&amp;ssl=1 683w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o9_1280.jpg?resize=320%2C480&amp;ssl=1 320w\" width=\"754\" height=\"1131\" loading=\"lazy\" data-original-width=\"754\" data-original-height=\"1131\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"\" style=\"width: 754px; height: 1131px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-3\" style=\"width: 442px; height: 1135px;\" data-original-width=\"442\" data-original-height=\"1135\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/attachment\/2605\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"438\"> <meta itemprop=\"height\" content=\"247\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2605\" data-orig-file=\"https:\/\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o1_1280.jpg\" data-orig-size=\"1200,675\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1431082267&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.9&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.0008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o1_1280.jpg?fit=720%2C405&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o1_1280.jpg?fit=1024%2C576&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o1_1280.jpg?w=438&#038;h=247&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o1_1280.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o1_1280.jpg?resize=720%2C405&amp;ssl=1 720w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o1_1280.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2lgws5On1sn9hw1o1_1280.jpg?resize=320%2C180&amp;ssl=1 320w\" width=\"438\" height=\"247\" loading=\"lazy\" data-original-width=\"438\" data-original-height=\"247\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"\" style=\"width: 438px; height: 247px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/detras-de-los-cerros-1\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"438\"> <meta itemprop=\"height\" content=\"438\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2695\" data-orig-file=\"https:\/\/media1.marcocueva.com\/detras-de-los-cerros-1.jpg\" data-orig-size=\"1200,1200\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;C6903&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1430989745&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.9&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.0008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"detras-de-los-cerros-1\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-1.jpg?fit=720%2C720&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-1.jpg?fit=1024%2C1024&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-1.jpg?w=438&#038;h=438&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-1.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-1.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-1.jpg?resize=720%2C720&amp;ssl=1 720w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-1.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-1.jpg?resize=50%2C50&amp;ssl=1 50w\" width=\"438\" height=\"438\" loading=\"lazy\" data-original-width=\"438\" data-original-height=\"438\" itemprop=\"http:\/\/schema.org\/image\" title=\"detras-de-los-cerros-1\" alt=\"detras-de-los-cerros-1\" style=\"width: 438px; height: 438px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/detras-de-los-cerros-2\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"438\"> <meta itemprop=\"height\" content=\"438\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2696\" data-orig-file=\"https:\/\/media1.marcocueva.com\/detras-de-los-cerros-2.jpg\" data-orig-size=\"1200,1200\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;C6903&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1431165469&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.9&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.000625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"detras-de-los-cerros-2\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-2.jpg?fit=720%2C720&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-2.jpg?fit=1024%2C1024&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-2.jpg?w=438&#038;h=438&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-2.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-2.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-2.jpg?resize=720%2C720&amp;ssl=1 720w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-2.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-2.jpg?resize=50%2C50&amp;ssl=1 50w\" width=\"438\" height=\"438\" loading=\"lazy\" data-original-width=\"438\" data-original-height=\"438\" itemprop=\"http:\/\/schema.org\/image\" title=\"detras-de-los-cerros-2\" alt=\"detras-de-los-cerros-2\" style=\"width: 438px; height: 438px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 296px;\" data-original-width=\"1200\" data-original-height=\"296\" > <div class=\"gallery-group images-1\" style=\"width: 522px; height: 296px;\" data-original-width=\"522\" data-original-height=\"296\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/detras-de-los-cerros-3\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"518\"> <meta itemprop=\"height\" content=\"292\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2697\" data-orig-file=\"https:\/\/media1.marcocueva.com\/detras-de-los-cerros-3.jpg\" data-orig-size=\"1200,675\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;C6903&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1431170670&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.9&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.0008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"detras-de-los-cerros-3\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-3.jpg?fit=720%2C405&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-3.jpg?fit=1024%2C576&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-3.jpg?w=518&#038;h=292&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-3.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-3.jpg?resize=720%2C405&amp;ssl=1 720w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-3.jpg?resize=1024%2C576&amp;ssl=1 1024w\" width=\"518\" height=\"292\" loading=\"lazy\" data-original-width=\"518\" data-original-height=\"292\" itemprop=\"http:\/\/schema.org\/image\" title=\"detras-de-los-cerros-3\" alt=\"detras-de-los-cerros-3\" style=\"width: 518px; height: 292px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 296px; height: 296px;\" data-original-width=\"296\" data-original-height=\"296\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/detras-de-los-cerros-4\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"292\"> <meta itemprop=\"height\" content=\"292\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2698\" data-orig-file=\"https:\/\/media1.marcocueva.com\/detras-de-los-cerros-4.jpg\" data-orig-size=\"1200,1200\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;C6903&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1431174915&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.9&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.001&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"detras-de-los-cerros-4\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-4.jpg?fit=720%2C720&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-4.jpg?fit=1024%2C1024&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-4.jpg?w=292&#038;h=292&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-4.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-4.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-4.jpg?resize=720%2C720&amp;ssl=1 720w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-4.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-4.jpg?resize=50%2C50&amp;ssl=1 50w\" width=\"292\" height=\"292\" loading=\"lazy\" data-original-width=\"292\" data-original-height=\"292\" itemprop=\"http:\/\/schema.org\/image\" title=\"detras-de-los-cerros-4\" alt=\"detras-de-los-cerros-4\" style=\"width: 292px; height: 292px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 382px; height: 296px;\" data-original-width=\"382\" data-original-height=\"296\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/detras-de-los-cerros-5\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"378\"> <meta itemprop=\"height\" content=\"292\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2699\" data-orig-file=\"https:\/\/media1.marcocueva.com\/detras-de-los-cerros-5.jpg\" data-orig-size=\"1200,927\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;C6903&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1431184558&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.9&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.00025&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"detras-de-los-cerros-5\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-5.jpg?fit=720%2C556&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-5.jpg?fit=1024%2C791&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-5.jpg?w=378&#038;h=292&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-5.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-5.jpg?resize=720%2C556&amp;ssl=1 720w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-5.jpg?resize=1024%2C791&amp;ssl=1 1024w\" width=\"378\" height=\"292\" loading=\"lazy\" data-original-width=\"378\" data-original-height=\"292\" itemprop=\"http:\/\/schema.org\/image\" title=\"detras-de-los-cerros-5\" alt=\"detras-de-los-cerros-5\" style=\"width: 378px; height: 292px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 608px;\" data-original-width=\"1200\" data-original-height=\"608\" > <div class=\"gallery-group images-1\" style=\"width: 809px; height: 608px;\" data-original-width=\"809\" data-original-height=\"608\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/detras-de-los-cerros-6\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"805\"> <meta itemprop=\"height\" content=\"604\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2700\" data-orig-file=\"https:\/\/media1.marcocueva.com\/detras-de-los-cerros-6.jpg\" data-orig-size=\"1200,900\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;C6903&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1431442685&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.9&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.0005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"detras-de-los-cerros-6\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-6.jpg?fit=720%2C540&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-6.jpg?fit=1024%2C768&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-6.jpg?w=805&#038;h=604&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-6.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-6.jpg?resize=720%2C540&amp;ssl=1 720w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-6.jpg?resize=1024%2C768&amp;ssl=1 1024w\" width=\"805\" height=\"604\" loading=\"lazy\" data-original-width=\"805\" data-original-height=\"604\" itemprop=\"http:\/\/schema.org\/image\" title=\"detras-de-los-cerros-6\" alt=\"detras-de-los-cerros-6\" style=\"width: 805px; height: 604px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 391px; height: 608px;\" data-original-width=\"391\" data-original-height=\"608\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/detras-de-los-cerros-7\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"387\"> <meta itemprop=\"height\" content=\"290\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2701\" data-orig-file=\"https:\/\/media1.marcocueva.com\/detras-de-los-cerros-7.jpg\" data-orig-size=\"1200,900\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;C6903&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1431520010&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.9&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.0015625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"detras-de-los-cerros-7\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-7.jpg?fit=720%2C540&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-7.jpg?fit=1024%2C768&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-7.jpg?w=387&#038;h=290&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-7.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-7.jpg?resize=720%2C540&amp;ssl=1 720w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-7.jpg?resize=1024%2C768&amp;ssl=1 1024w\" width=\"387\" height=\"290\" loading=\"lazy\" data-original-width=\"387\" data-original-height=\"290\" itemprop=\"http:\/\/schema.org\/image\" title=\"detras-de-los-cerros-7\" alt=\"detras-de-los-cerros-7\" style=\"width: 387px; height: 290px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/detras-de-los-cerros-8\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"387\"> <meta itemprop=\"height\" content=\"310\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2702\" data-orig-file=\"https:\/\/media1.marcocueva.com\/detras-de-los-cerros-8.jpg\" data-orig-size=\"1200,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;C6903&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1431529224&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.9&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.0004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"detras-de-los-cerros-8\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-8.jpg?fit=720%2C576&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-8.jpg?fit=1024%2C819&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-8.jpg?w=387&#038;h=310&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-8.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-8.jpg?resize=720%2C576&amp;ssl=1 720w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-8.jpg?resize=1024%2C819&amp;ssl=1 1024w\" width=\"387\" height=\"310\" loading=\"lazy\" data-original-width=\"387\" data-original-height=\"310\" itemprop=\"http:\/\/schema.org\/image\" title=\"detras-de-los-cerros-8\" alt=\"detras-de-los-cerros-8\" style=\"width: 387px; height: 310px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 687px;\" data-original-width=\"1200\" data-original-height=\"687\" > <div class=\"gallery-group images-2\" style=\"width: 513px; height: 687px;\" data-original-width=\"513\" data-original-height=\"687\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/detras-de-los-cerros-10\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"509\"> <meta itemprop=\"height\" content=\"340\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2703\" data-orig-file=\"https:\/\/media1.marcocueva.com\/detras-de-los-cerros-10.jpg\" data-orig-size=\"1200,800\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;C6903&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1431801262&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.9&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.00125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"detras-de-los-cerros-10\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-10.jpg?fit=720%2C480&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-10.jpg?fit=1024%2C683&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-10.jpg?w=509&#038;h=340&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-10.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-10.jpg?resize=720%2C480&amp;ssl=1 720w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-10.jpg?resize=1024%2C683&amp;ssl=1 1024w\" width=\"509\" height=\"340\" loading=\"lazy\" data-original-width=\"509\" data-original-height=\"340\" itemprop=\"http:\/\/schema.org\/image\" title=\"detras-de-los-cerros-10\" alt=\"detras-de-los-cerros-10\" style=\"width: 509px; height: 340px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/detras-de-los-cerros-11\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"509\"> <meta itemprop=\"height\" content=\"339\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2704\" data-orig-file=\"https:\/\/media1.marcocueva.com\/detras-de-los-cerros-11.jpg\" data-orig-size=\"1200,800\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;C6903&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1431802336&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.9&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.001&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"detras-de-los-cerros-11\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-11.jpg?fit=720%2C480&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-11.jpg?fit=1024%2C683&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-11.jpg?w=509&#038;h=339&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-11.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-11.jpg?resize=720%2C480&amp;ssl=1 720w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-11.jpg?resize=1024%2C683&amp;ssl=1 1024w\" width=\"509\" height=\"339\" loading=\"lazy\" data-original-width=\"509\" data-original-height=\"339\" itemprop=\"http:\/\/schema.org\/image\" title=\"detras-de-los-cerros-11\" alt=\"detras-de-los-cerros-11\" style=\"width: 509px; height: 339px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 687px; height: 687px;\" data-original-width=\"687\" data-original-height=\"687\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/detras-de-los-cerros-12\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"683\"> <meta itemprop=\"height\" content=\"683\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2705\" data-orig-file=\"https:\/\/media1.marcocueva.com\/detras-de-los-cerros-12.jpg\" data-orig-size=\"1200,1200\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;C6903&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1431973306&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.9&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.0003125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"detras-de-los-cerros-12\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-12.jpg?fit=720%2C720&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-12.jpg?fit=1024%2C1024&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-12.jpg?w=683&#038;h=683&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-12.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-12.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-12.jpg?resize=720%2C720&amp;ssl=1 720w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-12.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-12.jpg?resize=50%2C50&amp;ssl=1 50w\" width=\"683\" height=\"683\" loading=\"lazy\" data-original-width=\"683\" data-original-height=\"683\" itemprop=\"http:\/\/schema.org\/image\" title=\"detras-de-los-cerros-12\" alt=\"detras-de-los-cerros-12\" style=\"width: 683px; height: 683px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 440px;\" data-original-width=\"1200\" data-original-height=\"440\" > <div class=\"gallery-group images-1\" style=\"width: 615px; height: 440px;\" data-original-width=\"615\" data-original-height=\"440\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/detras-de-los-cerros-13\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"611\"> <meta itemprop=\"height\" content=\"436\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2706\" data-orig-file=\"https:\/\/media1.marcocueva.com\/detras-de-los-cerros-13.jpg\" data-orig-size=\"1200,857\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;C6903&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1432148872&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.9&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.0005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"detras-de-los-cerros-13\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-13.jpg?fit=720%2C514&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-13.jpg?fit=1024%2C731&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-13.jpg?w=611&#038;h=436&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-13.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-13.jpg?resize=720%2C514&amp;ssl=1 720w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-13.jpg?resize=1024%2C731&amp;ssl=1 1024w\" width=\"611\" height=\"436\" loading=\"lazy\" data-original-width=\"611\" data-original-height=\"436\" itemprop=\"http:\/\/schema.org\/image\" title=\"detras-de-los-cerros-13\" alt=\"detras-de-los-cerros-13\" style=\"width: 611px; height: 436px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 585px; height: 440px;\" data-original-width=\"585\" data-original-height=\"440\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad\/detras-de-los-cerros-14\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"581\"> <meta itemprop=\"height\" content=\"436\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"2707\" data-orig-file=\"https:\/\/media1.marcocueva.com\/detras-de-los-cerros-14.jpg\" data-orig-size=\"1200,900\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;C6903&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1432148896&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.9&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.0005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"detras-de-los-cerros-14\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-14.jpg?fit=720%2C540&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-14.jpg?fit=1024%2C768&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-14.jpg?w=581&#038;h=436&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-14.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-14.jpg?resize=720%2C540&amp;ssl=1 720w, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-de-los-cerros-14.jpg?resize=1024%2C768&amp;ssl=1 1024w\" width=\"581\" height=\"436\" loading=\"lazy\" data-original-width=\"581\" data-original-height=\"436\" itemprop=\"http:\/\/schema.org\/image\" title=\"detras-de-los-cerros-14\" alt=\"detras-de-los-cerros-14\" style=\"width: 581px; height: 436px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div><\/p>\n<p><strong>\u201cDetr\u00e1s de los Cerros\u201d:<\/strong><\/p>\n<p>Un proyecto para el hogar de ancianos de Oskarslund, Karlstad<\/p>\n<p><a href=\"http:\/\/centroescultura.wordpress.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Centro Internacional de Escultura<\/a> <br \/>Odrinhas, Portugal 2015<\/p>\n<p><\/p>\n<div class=\"gallery-frame \">","protected":false},"excerpt":{"rendered":"<p>\u201cDetr\u00e1s de los Cerros\u201d: Un proyecto para el hogar de ancianos de Oskarslund, Karlstad Centro Internacional de Escultura Odrinhas, Portugal 2015<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17,13,18],"tags":[111,213,141,155,161,170],"class_list":["post-2595","post","type-post","status-publish","format-gallery","hentry","category-public-works","category-work","category-work-in-progress","tag-marble","tag-oskarslund","tag-public-art","tag-sculpture","tag-stone","tag-work-in-progress","post_format-post-format-gallery"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p63sn4-FR","jetpack-related-posts":[{"id":2607,"url":"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-oskarslund-karlstad-2\/","url_meta":{"origin":2595,"position":0},"title":"Trabajo en Curso","author":"Marco Cueva","date":"mayo 9, 2015","format":"gallery","excerpt":"\u201cDetras de los Cerros\u201d Oskarslund, Karlstad","rel":"","context":"En \u00abObra P\u00fablica\u00bb","block_context":{"text":"Obra P\u00fablica","link":"https:\/\/marcocueva.com\/es\/category\/work\/public-works\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_no2l7e4Qdx1sn9hw1o1_1280.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3031,"url":"https:\/\/marcocueva.com\/es\/detras-de-los-cerros-the-final-push\/","url_meta":{"origin":2595,"position":1},"title":"\u00bbDetr\u00e1s de los Cerros\u00bb (El \u00faltimo empuj\u00f3n)","author":"Marco Cueva","date":"octubre 16, 2015","format":"gallery","excerpt":"Un \u00faltimo esfuerzo para terminar Detr\u00e1s de los Cerros: Un grupo de esculturas para el Hogar de ancianos de Oskarslund, Karlstad. Muchas veces he preferido actuar antes de pensar y corregir mis errores sobre la marcha\u00a0pero en esta obra el margen de error tuvo que mantenerse al minimo. Me vi\u2026","rel":"","context":"En \u00abObra P\u00fablica\u00bb","block_context":{"text":"Obra P\u00fablica","link":"https:\/\/marcocueva.com\/es\/category\/work\/public-works\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-151015-02.jpg?fit=900%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-151015-02.jpg?fit=900%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-151015-02.jpg?fit=900%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/media1.marcocueva.com\/detras-151015-02.jpg?fit=900%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2912,"url":"https:\/\/marcocueva.com\/es\/portugal-part-iii\/","url_meta":{"origin":2595,"position":2},"title":"Portugal, Tercera Parte","author":"Marco Cueva","date":"septiembre 8, 2015","format":"gallery","excerpt":"Despu\u00e9s de dos semanas de trabajo sin parar, termin\u00e9 las seis partes de piedra \"Detr\u00e1s de los Cerros\", una comisi\u00f3n para la ciudad de Karlstad. Centro Internacional de Escultura, Odrinhas \u00a0Septiembre 2015","rel":"","context":"En \u00abLugares\u00bb","block_context":{"text":"Lugares","link":"https:\/\/marcocueva.com\/es\/category\/impressions\/places\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/media1.marcocueva.com\/odrinhas-ptIII-150906-00729.jpg?fit=1200%2C730&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/media1.marcocueva.com\/odrinhas-ptIII-150906-00729.jpg?fit=1200%2C730&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/media1.marcocueva.com\/odrinhas-ptIII-150906-00729.jpg?fit=1200%2C730&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/media1.marcocueva.com\/odrinhas-ptIII-150906-00729.jpg?fit=1200%2C730&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/media1.marcocueva.com\/odrinhas-ptIII-150906-00729.jpg?fit=1200%2C730&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3685,"url":"https:\/\/marcocueva.com\/es\/portugal-for-the-last-time\/","url_meta":{"origin":2595,"position":3},"title":"Portugal, por la ultima vez?","author":"Marco Cueva","date":"abril 7, 2016","format":"gallery","excerpt":"Yo pens\u00e9 que ya estaba listo con mi trabajo para la C\u00e1mara Municipal de Karlstad pero me toc\u00f3 que regresar a Odrinhas, un peque\u00f1o pueblo al norte de Sintra y hacer una nueva nube de m\u00e1rmol para reforzar la estabilidad del grupo de esculturas \"Detr\u00e1s de los Cerros\"","rel":"","context":"En \u00abLugares\u00bb","block_context":{"text":"Lugares","link":"https:\/\/marcocueva.com\/es\/category\/impressions\/places\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/media1.marcocueva.com\/ericeira-58.jpg?fit=1200%2C571&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/media1.marcocueva.com\/ericeira-58.jpg?fit=1200%2C571&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/media1.marcocueva.com\/ericeira-58.jpg?fit=1200%2C571&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/media1.marcocueva.com\/ericeira-58.jpg?fit=1200%2C571&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/media1.marcocueva.com\/ericeira-58.jpg?fit=1200%2C571&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":2120,"url":"https:\/\/marcocueva.com\/es\/proposal-2\/","url_meta":{"origin":2595,"position":4},"title":"Proposal","author":"Marco Cueva","date":"noviembre 24, 2014","format":"gallery","excerpt":"Propuesta para Oskarslunds V\u00e5rdboende, Karlstad","rel":"","context":"En \u00abObra P\u00fablica\u00bb","block_context":{"text":"Obra P\u00fablica","link":"https:\/\/marcocueva.com\/es\/category\/work\/public-works\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_nfk9k0tEpD1sn9hw1o1_1280.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2064,"url":"https:\/\/marcocueva.com\/es\/work-in-progress-142\/","url_meta":{"origin":2595,"position":5},"title":"Trabajos en Curso","author":"Marco Cueva","date":"octubre 15, 2014","format":"gallery","excerpt":"Trabajo en curso, maqueta para \"Detr\u00e1s de los Cerros\"","rel":"","context":"En \u00abObra P\u00fablica\u00bb","block_context":{"text":"Obra P\u00fablica","link":"https:\/\/marcocueva.com\/es\/category\/work\/public-works\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/media1.marcocueva.com\/tumblr_ndh9h35u591sn9hw1o1_1280.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/posts\/2595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/comments?post=2595"}],"version-history":[{"count":4,"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/posts\/2595\/revisions"}],"predecessor-version":[{"id":4287,"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/posts\/2595\/revisions\/4287"}],"wp:attachment":[{"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/media?parent=2595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/categories?post=2595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/tags?post=2595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}