{"id":463,"date":"2013-05-12T00:00:23","date_gmt":"2013-05-11T22:00:23","guid":{"rendered":"http:\/\/blogg.marcocueva.com\/?p=463"},"modified":"2020-09-22T00:33:09","modified_gmt":"2020-09-21T22:33:09","slug":"hercobulus","status":"publish","type":"post","link":"https:\/\/marcocueva.com\/es\/hercobulus\/","title":{"rendered":"Herc\u00f3bulus"},"content":{"rendered":"<p style=\"text-align: center;\">El Principio del Fin<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/blogg.marcocueva.com\/zenphoto\/\/index.php?album=procesos\/nibiru\"><img decoding=\"async\" class=\"ZenphotoPress_thumb \" title=\"Nibiru\" alt=\"Nibiru\" src=\"http:\/\/blogg.marcocueva.com\/zenphoto\/\/zp-core\/i.php?a=procesos\/nibiru&amp;i=nibiru-124126.jpg&amp;w=400&amp;h=\" \/><\/a><\/p>\n<p style=\"text-align: center;\">anteriormente las engrapaba lo cual resultaba en trabajo extra.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/blogg.marcocueva.com\/zenphoto\/\/index.php?album=procesos\/nibiru&amp;image=nibiru-_1328563026.jpg\"><img decoding=\"async\" class=\"ZenphotoPress_thumb \" title=\"nibiru\" alt=\"nibiru\" src=\"http:\/\/blogg.marcocueva.com\/zenphoto\/\/zp-core\/i.php?a=procesos\/nibiru&amp;i=nibiru-_1328563026.jpg&amp;w=120&amp;h=\" \/><\/a>\u00a0 \u00a0 \u00a0<a href=\"http:\/\/blogg.marcocueva.com\/zenphoto\/\/index.php?album=procesos\/nibiru&amp;image=nibiru-1.jpg\"><img decoding=\"async\" class=\"ZenphotoPress_thumb \" title=\"nibiru-1\" alt=\"nibiru-1\" src=\"http:\/\/blogg.marcocueva.com\/zenphoto\/\/zp-core\/i.php?a=procesos\/nibiru&amp;i=nibiru-1.jpg&amp;w=120&amp;h=\" \/><\/a>\u00a0 \u00a0\u00a0<a href=\"http:\/\/blogg.marcocueva.com\/zenphoto\/\/index.php?album=procesos\/nibiru&amp;image=nibiru-1-8.jpg\"><img decoding=\"async\" class=\"ZenphotoPress_thumb \" title=\"nibiru-1-8\" alt=\"nibiru-1-8\" src=\"http:\/\/blogg.marcocueva.com\/zenphoto\/\/zp-core\/i.php?a=procesos\/nibiru&amp;i=nibiru-1-8.jpg&amp;w=120&amp;h=\" \/><\/a><br \/>\n<!--more--><\/p>\n<p style=\"text-align: center;\">Cuando iba para Honduras vi la pel\u00edcula Melancholia de \u00a0Lars Von Trier y la verdad que me impact\u00f3 un poco o mucho talv\u00e9s, ya en Honduras camino a Cop\u00e1n hab\u00edan varios\u00a0r\u00f3tulos\u00a0del libro de Hercobulus, que supuestamente predice el fin del mundo para este a\u00f1o, 2012 (en Cop\u00e1n los hoteles ya estan llenos pra el 121 de Diciembre). \u00a0Bueno la cosa que hay una frase en el film que \u00a0le va muy bien a la escultura en la que he estado trabajando ultimamente: <strong>Nibiru<\/strong><\/p>\n<div class=\"gallery-frame \">","protected":false},"excerpt":{"rendered":"<p>El Principio del Fin anteriormente las engrapaba lo cual resultaba en trabajo extra. \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[13,18],"tags":[76,94,124],"class_list":["post-463","post","type-post","status-publish","format-standard","hentry","category-work","category-work-in-progress","tag-escatologias","tag-hercobulus","tag-nibiru-2"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p63sn4-7t","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/posts\/463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/comments?post=463"}],"version-history":[{"count":1,"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/posts\/463\/revisions"}],"predecessor-version":[{"id":2353,"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/posts\/463\/revisions\/2353"}],"wp:attachment":[{"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/media?parent=463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/categories?post=463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcocueva.com\/es\/wp-json\/wp\/v2\/tags?post=463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}