{"id":4944,"date":"2024-05-12T20:53:42","date_gmt":"2024-05-12T18:53:42","guid":{"rendered":"http:\/\/media1.marcocueva.com\/Rannebergen-16-1.jpg"},"modified":"2024-05-12T22:18:11","modified_gmt":"2024-05-12T20:18:11","slug":"rannebergen-16-2","status":"inherit","type":"attachment","link":"https:\/\/marcocueva.com\/sv\/rannebergen-16-2\/","title":{"rendered":"Nandhi"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"categories":[],"tags":[],"class_list":["post-4944","attachment","type-attachment","status-inherit","hentry"],"jetpack_shortlink":"https:\/\/wp.me\/a63sn4-1hK","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-16-1-scaled.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"720\" src=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-16-1-scaled.jpg?fit=540%2C720&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"Nandhi\" srcset=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-16-1-scaled.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-16-1-scaled.jpg?resize=540%2C720&amp;ssl=1 540w, https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-16-1-scaled.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-16-1-scaled.jpg?resize=1152%2C1536&amp;ssl=1 1152w, https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-16-1-scaled.jpg?resize=1536%2C2048&amp;ssl=1 1536w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" data-attachment-id=\"4944\" data-permalink=\"https:\/\/marcocueva.com\/sv\/rannebergen-16-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-16-1-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 13 Pro Max&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1695904566&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;5.7&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.0028571428571429&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;,&quot;exposure_bias&quot;:&quot;0\/1&quot;,&quot;flash&quot;:&quot;16&quot;}\" data-image-title=\"Nandhi\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;&amp;#8221;Nandhi&amp;#8221; Rannebergen, G\u00f6teborg&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-16-1-scaled.jpg?fit=768%2C1024&amp;ssl=1\" \/><\/a><\/p>\n<div class=\"gallery-frame \">"},"caption":{"rendered":"<p>&#8221;Nandhi&#8221; Rannebergen, G\u00f6teborg<\/p>\n"},"alt_text":"Nandhi","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":2560,"file":"Rannebergen-16-1-scaled.jpg","filesize":759271,"sizes":{"medium":{"file":"Rannebergen-16-1-540x720.jpg","width":540,"height":720,"filesize":103999,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-16-1-scaled.jpg?fit=540%2C720&ssl=1"},"large":{"file":"Rannebergen-16-1-768x1024.jpg","width":768,"height":1024,"filesize":170798,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-16-1-scaled.jpg?fit=768%2C1024&ssl=1"},"thumbnail":{"file":"Rannebergen-16-1-150x150.jpg","width":150,"height":150,"filesize":35730,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-16-1-scaled.jpg?resize=150%2C150&ssl=1"},"medium_large":{"file":"Rannebergen-16-1-768x1024.jpg","width":768,"height":1024,"filesize":170798,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-16-1-scaled.jpg?fit=768%2C1024&ssl=1"},"1536x1536":{"file":"Rannebergen-16-1-1152x1536.jpg","width":1152,"height":1536,"filesize":325403,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-16-1-scaled.jpg?fit=1152%2C1536&ssl=1"},"2048x2048":{"file":"Rannebergen-16-1-1536x2048.jpg","width":1536,"height":2048,"filesize":525102,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-16-1-scaled.jpg?fit=1536%2C2048&ssl=1"},"jetpack-portfolio-admin-thumb":{"file":"Rannebergen-16-1-50x50.jpg","width":50,"height":50,"filesize":30031,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-16-1-scaled.jpg?resize=50%2C50&ssl=1"},"full":{"file":"Rannebergen-16-1-scaled.jpg?fit=1920%2C2560&ssl=1","width":1920,"height":2560,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/media1.marcocueva.com\/Rannebergen-16-1-scaled.jpg?fit=1920%2C2560&ssl=1"}},"image_meta":{"aperture":"1.5","credit":"","camera":"iPhone 13 Pro Max","caption":"","created_timestamp":"1695904566","copyright":"","focal_length":"5.7","iso":"50","shutter_speed":"0.0028571428571429","title":"","orientation":"0","keywords":[],"exposure_bias":"0\/1","flash":"16"},"original_image":"Rannebergen-16-1.jpg"},"post":null,"source_url":"https:\/\/media1.marcocueva.com\/Rannebergen-16-1-scaled.jpg","_links":{"self":[{"href":"https:\/\/marcocueva.com\/sv\/wp-json\/wp\/v2\/media\/4944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcocueva.com\/sv\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/marcocueva.com\/sv\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/marcocueva.com\/sv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/marcocueva.com\/sv\/wp-json\/wp\/v2\/comments?post=4944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcocueva.com\/sv\/wp-json\/wp\/v2\/categories?post=4944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcocueva.com\/sv\/wp-json\/wp\/v2\/tags?post=4944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}